{"id":29805,"date":"2024-02-20T09:02:05","date_gmt":"2024-02-20T00:02:05","guid":{"rendered":"https:\/\/www.sena.com\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/"},"modified":"2024-02-20T10:02:34","modified_gmt":"2024-02-20T01:02:34","slug":"sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3","status":"publish","type":"post_notice","link":"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/","title":{"rendered":"SENA RILASCIA AGGIORNAMENTI DEL FIRMWARE PER SPIDER ST1 E SPIDER RT1"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">SPIDER ST1 Firmware v2.2 (per la versione 2022 di SPIDER ST1)<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Aggiunto un messaggio vocale per il livello della batteria dopo l&#8217;accensione del dispositivo.<br>\u2022\u00a0\u00a0Gli utenti possono ora annullare quando le cuffie entrano automaticamente in &#8220;Accoppiamento telefono&#8221; toccando un pulsante qualsiasi.<br>\u2022\u00a0\u00a0Eliminata la funzione &#8220;annulla&#8221; per tutte le modalit\u00e0 di accoppiamento, ad eccezione di &#8220;Accoppiamento telefono&#8221;, all&#8217;accensione del dispositivo.<br>\u2022\u00a0\u00a0Aggiunta di un segnale acustico quando si entra in &#8220;Accoppiamento telefono&#8221; premendo il pulsante Telefono per 5 secondi.<br>\u2022\u00a0\u00a0\u00c8 stato aggiunto il supporto per l&#8217;aggiornamento del firmware del dispositivo via etere (OTA).<br>\u2022\u00a0\u00a0Correzione di un bug che causava lo spegnimento casuale del dispositivo<br>\u2022\u00a0\u00a0Correzione di un bug che causava lo spegnimento del dispositivo quando si entrava in &#8220;Accoppiamento con telecomando&#8221;.<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;interfono Mesh quando si effettua o si termina una chiamata telefonica durante l&#8217;interfono Mesh.<br>\u2022\u00a0\u00a0Correzione di un bug relativo alla riconnessione alla versione 2022 di RC4<br>\u2022\u00a0\u00a0Correzione di un bug relativo al volume dopo l&#8217;esecuzione di un reset di fabbrica<br>\u2022\u00a0\u00a0Correzione di un bug relativo alla ricarica completa del dispositivo<br>\u2022\u00a0\u00a0Correzione di un bug relativo la ricezione di un avviso di chiamata in entrata\u00a0 durante l&#8217;utilizzo di Mesh Intercom<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;utilizzo di Mesh Intercom durante l&#8217;ascolto delle indicazioni GPS<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;ascolto di musica in streaming Bluetooth durante l&#8217;ascolto di indicazioni stradali da un&#8217;applicazione GPS<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;utilizzo di dispositivi GPS Garmin durante l&#8217;utilizzo di Mesh Intercom<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;attivazione e alla disattivazione ripetuta dell&#8217;interfonico Mesh<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SPIDER ST1 Firmware v2.2.1 (per la versione 2022 di SPIDER ST1)<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Correzzione di un Bug relativo la ricezione degli utenti vicini anche se la funzione Mesh Reach-Out \u00e8 stata disabilitata<br>\u2022\u00a0\u00a0Correzione di un bug relativo al controllo del volume sul dispositivo quando si mette un controllo remoto Sena in stand-by.<br>\u2022\u00a0\u00a0Correzione di un bug relativo allo spegnimento automatico del dispositivo quando si usa l&#8217;app Sena Motorcycles per iOS.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SPIDER RT1 Firmware v2.2 (per la versione 2022 di SPIDER RT1)<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Aggiunto un messaggio vocale per il livello della batteria dopo l&#8217;accensione del dispositivo.<br>\u2022\u00a0\u00a0Gli utenti possono ora annullare quando le cuffie entrano automaticamente in &#8220;Accoppiamento telefono&#8221; toccando un pulsante qualsiasi.<br>\u2022\u00a0\u00a0Eliminata la funzione &#8220;annulla&#8221; per tutte le modalit\u00e0 di accoppiamento, ad eccezione di &#8220;Accoppiamento telefono&#8221;, all&#8217;accensione del dispositivo.<br>\u2022\u00a0\u00a0Aggiunta di un segnale acustico quando si entra in &#8220;Accoppiamento telefono&#8221; premendo il pulsante Telefono per 5 secondi.<br>\u2022\u00a0\u00a0\u00c8 stato aggiunto il supporto per l&#8217;aggiornamento del firmware del dispositivo via etere (OTA).<br>\u2022\u00a0\u00a0Correzione di un bug che causava lo spegnimento casuale del dispositivo<br>\u2022\u00a0\u00a0Correzione di un bug che causava lo spegnimento del dispositivo quando si entrava in &#8220;Accoppiamento con telecomando&#8221;.<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;interfono Mesh quando si effettua o si termina una chiamata telefonica durante l&#8217;interfono Mesh.<br>\u2022\u00a0\u00a0Correzione di un bug relativo alla riconnessione alla versione 2022 di RC4<br>\u2022\u00a0\u00a0Correzione di un bug relativo al volume dopo l&#8217;esecuzione di un reset di fabbrica<br>\u2022\u00a0\u00a0Correzione di un bug relativo alla ricarica completa del dispositivo<br>\u2022\u00a0\u00a0Correzione di un bug relativo la ricezione di un avviso di chiamata in entrata\u00a0 durante l&#8217;utilizzo di Mesh Intercom<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;utilizzo di Mesh Intercom durante l&#8217;ascolto delle indicazioni GPS<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;ascolto di musica in streaming Bluetooth durante l&#8217;ascolto di indicazioni stradali da un&#8217;applicazione GPS<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;utilizzo di dispositivi GPS Garmin durante l&#8217;utilizzo di Mesh Intercom<br>\u2022\u00a0\u00a0Correzione di un bug relativo all&#8217;attivazione e alla disattivazione ripetuta dell&#8217;interfonico Mesh<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SPIDER RT1 Firmware v2.2.1 (per la versione 2022 di SPIDER RT1)<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Correzzione di un Bug relativo la ricezione degli utenti vicini anche se la funzione Mesh Reach-Out \u00e8 stata disabilitata<br>\u2022\u00a0\u00a0Correzione di un bug relativo al controllo del volume sul dispositivo quando si mette un controllo remoto Sena in stand-by.<br>\u2022\u00a0\u00a0Correzione di un bug relativo allo spegnimento automatico del dispositivo quando si usa l&#8217;app Sena Motorcycles per iOS.<\/p>\n","protected":false},"featured_media":0,"template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SENA RILASCIA AGGIORNAMENTI DEL FIRMWARE PER SPIDER ST1 E SPIDER RT1 - SENA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Best Motorcycle &amp; Action Sport Bluetooth Devices | Sena\" \/>\n<meta property=\"og:description\" content=\"Sena&#039;s motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/\" \/>\n<meta property=\"og:site_name\" content=\"SENA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SenaBluetooth\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-20T01:02:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sena.com\/wp-content\/themes\/sena\/assets\/images\/common\/og.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"SENA RILASCIA AGGIORNAMENTI DEL FIRMWARE PER SPIDER ST1 E SPIDER RT1\" \/>\n<meta name=\"twitter:site\" content=\"@senabluetooth\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/\",\"url\":\"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/\",\"name\":\"SENA RILASCIA AGGIORNAMENTI DEL FIRMWARE PER SPIDER ST1 E SPIDER RT1 - SENA\",\"isPartOf\":{\"@id\":\"https:\/\/www.sena.com\/#website\"},\"datePublished\":\"2024-02-20T00:02:05+00:00\",\"dateModified\":\"2024-02-20T01:02:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sena.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SENA RILASCIA AGGIORNAMENTI DEL FIRMWARE PER SPIDER ST1 E SPIDER RT1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sena.com\/#website\",\"url\":\"https:\/\/www.sena.com\/\",\"name\":\"SENA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.sena.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sena.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sena.com\/#organization\",\"name\":\"SENA\",\"url\":\"https:\/\/www.sena.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"contentUrl\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"width\":1,\"height\":1,\"caption\":\"SENA\"},\"image\":{\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SenaBluetooth\",\"https:\/\/twitter.com\/senabluetooth\",\"https:\/\/www.instagram.com\/senabluetooth\/\",\"https:\/\/www.youtube.com\/senabluetooth\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SENA RILASCIA AGGIORNAMENTI DEL FIRMWARE PER SPIDER ST1 E SPIDER RT1 - SENA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/","og_locale":"it_IT","og_type":"article","og_title":"The Best Motorcycle & Action Sport Bluetooth Devices | Sena","og_description":"Sena's motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.","og_url":"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/","og_site_name":"SENA","article_publisher":"https:\/\/www.facebook.com\/SenaBluetooth","article_modified_time":"2024-02-20T01:02:34+00:00","og_image":[{"url":"https:\/\/www.sena.com\/wp-content\/themes\/sena\/assets\/images\/common\/og.jpg","width":1200,"height":630,"type":""}],"twitter_card":"summary_large_image","twitter_title":"SENA RILASCIA AGGIORNAMENTI DEL FIRMWARE PER SPIDER ST1 E SPIDER RT1","twitter_site":"@senabluetooth","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/","url":"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/","name":"SENA RILASCIA AGGIORNAMENTI DEL FIRMWARE PER SPIDER ST1 E SPIDER RT1 - SENA","isPartOf":{"@id":"https:\/\/www.sena.com\/#website"},"datePublished":"2024-02-20T00:02:05+00:00","dateModified":"2024-02-20T01:02:34+00:00","breadcrumb":{"@id":"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sena.com\/it\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sena.com\/it\/"},{"@type":"ListItem","position":2,"name":"SENA RILASCIA AGGIORNAMENTI DEL FIRMWARE PER SPIDER ST1 E SPIDER RT1"}]},{"@type":"WebSite","@id":"https:\/\/www.sena.com\/#website","url":"https:\/\/www.sena.com\/","name":"SENA","description":"","publisher":{"@id":"https:\/\/www.sena.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sena.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.sena.com\/#organization","name":"SENA","url":"https:\/\/www.sena.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","contentUrl":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","width":1,"height":1,"caption":"SENA"},"image":{"@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SenaBluetooth","https:\/\/twitter.com\/senabluetooth","https:\/\/www.instagram.com\/senabluetooth\/","https:\/\/www.youtube.com\/senabluetooth"]}]}},"_links":{"self":[{"href":"https:\/\/www.sena.com\/it\/wp-json\/wp\/v2\/post_notice\/29805"}],"collection":[{"href":"https:\/\/www.sena.com\/it\/wp-json\/wp\/v2\/post_notice"}],"about":[{"href":"https:\/\/www.sena.com\/it\/wp-json\/wp\/v2\/types\/post_notice"}],"wp:attachment":[{"href":"https:\/\/www.sena.com\/it\/wp-json\/wp\/v2\/media?parent=29805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}