{"id":39872,"date":"2024-07-24T09:42:26","date_gmt":"2024-07-24T00:42:26","guid":{"rendered":"https:\/\/www.sena.com\/stories\/people\/heidi-sevestre-matthieu-tordeur\/"},"modified":"2024-08-05T11:04:16","modified_gmt":"2024-08-05T02:04:16","slug":"heidi-sevestre-matthieu-tordeur","status":"publish","type":"post_people","link":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/","title":{"rendered":"He\u00efdi Sevestre &amp; Matthieu Tordeur"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"h-presentation-de-heidi-et-matthieu\">Pr\u00e9sentation de He\u00efdi et Matthieu<\/h3>\n\n\n\n<p>He\u00efdi Sevestre et Matthieu Tordeur sont deux figures embl\u00e9matiques de l&#8217;exploration et de la recherche scientifique en milieu polaire. He\u00efdi, glaciologue de renomm\u00e9e internationale, s&#8217;est sp\u00e9cialis\u00e9e dans l&#8217;\u00e9tude des glaciers et des impacts du changement climatique. Matthieu, explorateur et plus jeune membre de la Soci\u00e9t\u00e9 des Explorateurs Fran\u00e7ais \u00e0 avoir atteint le p\u00f4le Sud en solitaire et sans assistance, combine ses comp\u00e9tences en aventure extr\u00eame et en collecte de donn\u00e9es scientifiques. Ensemble, ils forment un duo dynamique d\u00e9di\u00e9 \u00e0 la sensibilisation \u00e9cologique et \u00e0 la recherche sur les \u00e9cosyst\u00e8mes polaires.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.heidisevestre.com\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Website He\u00efdi<\/strong><\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/matthieutordeur.com\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Website Matthieu<\/strong><\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" data-id=\"40508\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img5-768x1024.jpg\" alt=\"\" class=\"wp-image-40508\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img5-768x1024.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img5-225x300.jpg 225w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img5-1152x1536.jpg 1152w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img5.jpg 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" data-id=\"40492\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img4-768x1024.jpg\" alt=\"\" class=\"wp-image-40492\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img4-768x1023.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img4-225x300.jpg 225w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img4.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-le-projet-et-l-importance-de-sena\">Le Projet et l&#8217;Importance de SENA<\/h3>\n\n\n\n<p>De 2024 \u00e0 2026, He\u00efdi et Matthieu entreprendront des exp\u00e9ditions ambitieuses au Groenland et en Antarctique. Leur projet vise \u00e0 sensibiliser le public aux d\u00e9fis environnementaux des r\u00e9gions polaires tout en recueillant des donn\u00e9es cruciales sur les effets du changement climatique. Pour garantir leur s\u00e9curit\u00e9 et une communication efficace dans des conditions climatiques extr\u00eames, SENA, leader mondial des intercoms, les \u00e9quipe avec le casque Latitude S1 et l&#8217;intercom Snowtalk 2. Ces \u00e9quipements permettent \u00e0 He\u00efdi et Matthieu de rester connect\u00e9s en permanence, m\u00eame dans les pires conditions de brouillard ou de temp\u00eate. He\u00efdi souligne l&#8217;importance de cette connexion : &#8220;Nous \u00e9changeons beaucoup tout au long de la journ\u00e9e gr\u00e2ce \u00e0 nos casques de ski Sena connect\u00e9s. On se tient au courant de la m\u00e9t\u00e9o, des conditions de neige, et cela nous permet m\u00eame d&#8217;\u00e9couter de la musique pour nous motiver.&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" data-id=\"40476\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img3-768x1024.jpg\" alt=\"\" class=\"wp-image-40476\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img3-768x1024.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img3-225x300.jpg 225w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img3.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"1024\" data-id=\"40460\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img2-768x1024.jpg\" alt=\"\" class=\"wp-image-40460\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img2-768x1024.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img2-225x300.jpg 225w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_img2.jpg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-l-importance-des-tests-sur-le-terrain-selon-sena\">L&#8217;Importance des Tests sur le Terrain selon SENA<\/h3>\n\n\n\n<p>Pour SENA, tester les produits sur le terrain est essentiel pour garantir leur performance et leur fiabilit\u00e9. &#8220;Pour nous, il est crucial de voir nos \u00e9quipements en action dans les conditions les plus extr\u00eames&#8221;, explique un repr\u00e9sentant de SENA. Les exp\u00e9ditions de He\u00efdi et Matthieu offrent une occasion parfaite pour cela. Les casques Latitude S1 et les intercoms Snowtalk 2, sp\u00e9cialement con\u00e7us pour les environnements polaires, permettent une communication claire, m\u00eame par vent fort, et offrent une longue port\u00e9e et une r\u00e9sistance aux intemp\u00e9ries. He\u00efdi appr\u00e9cie particuli\u00e8rement ces fonctionnalit\u00e9s : &#8220;Les casques nous permettent non seulement de rester en contact constant, mais aussi de nous distraire en \u00e9coutant de la musique pendant les longues heures de kite. Cela peut vraiment faire la diff\u00e9rence pour garder le moral et l&#8217;\u00e9nergie, surtout quand les jambes sont lourdes en fin de journ\u00e9e.&#8221; Gr\u00e2ce aux retours de terrain de He\u00efdi et Matthieu, SENA peut continuer \u00e0 am\u00e9liorer ses produits pour r\u00e9pondre aux besoins des aventuriers et des scientifiques, assurant ainsi leur s\u00e9curit\u00e9 et leur confort.<\/p>\n","protected":false},"featured_media":40524,"template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>He\u00efdi Sevestre &amp; Matthieu Tordeur - SENA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Best Motorcycle &amp; Action Sport Bluetooth Devices | Sena\" \/>\n<meta property=\"og:description\" content=\"Sena&#039;s motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/\" \/>\n<meta property=\"og:site_name\" content=\"SENA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SenaBluetooth\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-05T02:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_overview.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"He\u00efdi Sevestre &amp; Matthieu Tordeur\" \/>\n<meta name=\"twitter:site\" content=\"@senabluetooth\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/\",\"url\":\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/\",\"name\":\"He\u00efdi Sevestre &amp; Matthieu Tordeur - SENA\",\"isPartOf\":{\"@id\":\"https:\/\/www.sena.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_overview.jpg\",\"datePublished\":\"2024-07-24T00:42:26+00:00\",\"dateModified\":\"2024-08-05T02:04:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#primaryimage\",\"url\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_overview.jpg\",\"contentUrl\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_overview.jpg\",\"width\":980,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sena.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"He\u00efdi Sevestre &amp; Matthieu Tordeur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sena.com\/#website\",\"url\":\"https:\/\/www.sena.com\/\",\"name\":\"SENA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.sena.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sena.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sena.com\/#organization\",\"name\":\"SENA\",\"url\":\"https:\/\/www.sena.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"contentUrl\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"width\":1,\"height\":1,\"caption\":\"SENA\"},\"image\":{\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SenaBluetooth\",\"https:\/\/twitter.com\/senabluetooth\",\"https:\/\/www.instagram.com\/senabluetooth\/\",\"https:\/\/www.youtube.com\/senabluetooth\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"He\u00efdi Sevestre &amp; Matthieu Tordeur - SENA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/","og_locale":"fr_FR","og_type":"article","og_title":"The Best Motorcycle & Action Sport Bluetooth Devices | Sena","og_description":"Sena's motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.","og_url":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/","og_site_name":"SENA","article_publisher":"https:\/\/www.facebook.com\/SenaBluetooth","article_modified_time":"2024-08-05T02:04:16+00:00","og_image":[{"width":980,"height":550,"url":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_overview.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"He\u00efdi Sevestre &amp; Matthieu Tordeur","twitter_site":"@senabluetooth","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/","url":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/","name":"He\u00efdi Sevestre &amp; Matthieu Tordeur - SENA","isPartOf":{"@id":"https:\/\/www.sena.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#primaryimage"},"image":{"@id":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_overview.jpg","datePublished":"2024-07-24T00:42:26+00:00","dateModified":"2024-08-05T02:04:16+00:00","breadcrumb":{"@id":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#primaryimage","url":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_overview.jpg","contentUrl":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/07\/Matthieu_overview.jpg","width":980,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.sena.com\/fr\/stories\/people\/heidi-sevestre-matthieu-tordeur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sena.com\/fr\/"},{"@type":"ListItem","position":2,"name":"He\u00efdi Sevestre &amp; Matthieu Tordeur"}]},{"@type":"WebSite","@id":"https:\/\/www.sena.com\/#website","url":"https:\/\/www.sena.com\/","name":"SENA","description":"","publisher":{"@id":"https:\/\/www.sena.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sena.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.sena.com\/#organization","name":"SENA","url":"https:\/\/www.sena.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","contentUrl":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","width":1,"height":1,"caption":"SENA"},"image":{"@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SenaBluetooth","https:\/\/twitter.com\/senabluetooth","https:\/\/www.instagram.com\/senabluetooth\/","https:\/\/www.youtube.com\/senabluetooth"]}]}},"_links":{"self":[{"href":"https:\/\/www.sena.com\/fr\/wp-json\/wp\/v2\/post_people\/39872"}],"collection":[{"href":"https:\/\/www.sena.com\/fr\/wp-json\/wp\/v2\/post_people"}],"about":[{"href":"https:\/\/www.sena.com\/fr\/wp-json\/wp\/v2\/types\/post_people"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sena.com\/fr\/wp-json\/wp\/v2\/media\/40524"}],"wp:attachment":[{"href":"https:\/\/www.sena.com\/fr\/wp-json\/wp\/v2\/media?parent=39872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}