{"id":26598,"date":"2022-06-10T17:55:00","date_gmt":"2022-06-10T08:55:00","guid":{"rendered":"https:\/\/www.sena.com\/stories\/disclosure\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/"},"modified":"2024-01-31T10:53:31","modified_gmt":"2024-01-31T01:53:31","slug":"sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker","status":"publish","type":"post_notice","link":"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/","title":{"rendered":"SENA PUBLIE LE NOUVEAU FIRMWARE POUR LA S\u00c9RIE SPIDER, 50R, 50S, 5S, ET STRYKER"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>SPIDER RT1 v1.1.4 \/ SPIDER ST1 v1.1.4<\/strong><\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Am\u00e9lioration de la connectivit\u00e9 avec l&#8217;application Sena Motorcycles<br>\u2022\u00a0\u00a0Correction d&#8217;un bug mineur avec l&#8217;\u00e9galiseur lorsque le casque est red\u00e9marr\u00e9<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">50R v1.1.1<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Ajout de la prise en charge du Moto GPS Laser<br>\u2022\u00a0\u00a0Am\u00e9lioration de la prise en charge des t\u00e9l\u00e9commandes<br>\u2022\u00a0\u00a0Am\u00e9lioration de la connectivit\u00e9 avec l&#8217;application Sena Motorcycles<br>\u2022\u00a0\u00a0Temps de r\u00e9ponse am\u00e9lior\u00e9 du bouton de pause sur l&#8217;application Sena Motorcycles<br>\u2022\u00a0\u00a0Correction d&#8217;un bug mineur avec la superposition de Mesh Intercom pendant les appels t\u00e9l\u00e9phoniques avec un smartphone coupl\u00e9 \u00e0 l&#8217;aide du couplage Second Mobile Phone<br>\u2022\u00a0\u00a0Correction d&#8217;un bug mineur avec le bouton Mesh Intercom d\u00e9sactiv\u00e9 sur l&#8217;application Sena Motorcycles apr\u00e8s l&#8217;activation du num\u00e9roteur vocal \u00e0 l&#8217;aide des boutons du casque<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">50S v1.1.1<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Ajout de la prise en charge du Moto GPS Laser<br>\u2022\u00a0\u00a0Am\u00e9lioration de la prise en charge des t\u00e9l\u00e9commandes<br>\u2022\u00a0\u00a0Am\u00e9lioration de la connectivit\u00e9 avec l&#8217;application Sena Motorcycles<br>\u2022\u00a0\u00a0Temps de r\u00e9ponse am\u00e9lior\u00e9 du bouton de pause sur l&#8217;application Sena Motorcycles<br>\u2022\u00a0\u00a0Correction d&#8217;un bogue mineur avec la superposition de Mesh Intercom pendant les appels t\u00e9l\u00e9phoniques avec un smartphone coupl\u00e9 \u00e0 l&#8217;aide du couplage Second Mobile Phone<br>\u2022\u00a0\u00a0Correction d&#8217;un bug mineur avec le bouton Mesh Intercom d\u00e9sactiv\u00e9 sur l&#8217;application Sena Motorcycles apr\u00e8s l&#8217;activation du num\u00e9roteur vocal \u00e0 l&#8217;aide des boutons du casque<br>\u2022\u00a0\u00a0R\u00e9duction du volume maximal de sortie du port AUX OUT de 2 niveaux<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5S v2.1<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Prise en charge am\u00e9lior\u00e9e des t\u00e9l\u00e9commandes<br>\u2022\u00a0\u00a0Am\u00e9lioration de la connectivit\u00e9 avec l&#8217;application Sena Motorcycles<br>\u2022\u00a0\u00a0Correction d&#8217;un bug mineur pour supprimer les informations d&#8217;appariement pour les t\u00e9l\u00e9commandes apr\u00e8s avoir effectu\u00e9 une r\u00e9initialisation d&#8217;usine<br>\u2022\u00a0\u00a0Correction d&#8217;un bug mineur avec l&#8217;\u00e9galiseur lorsque le casque est red\u00e9marr\u00e9<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Stryker v1.0.3<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Temps de r\u00e9ponse am\u00e9lior\u00e9 du bouton de pause sur l&#8217;application Sena Motorcycles<br>\u2022\u00a0\u00a0Correction d&#8217;un bug mineur avec la superposition de Mesh Intercom pendant les appels t\u00e9l\u00e9phoniques avec un smartphone coupl\u00e9 \u00e0 l&#8217;aide du couplage Second Mobile Phone<br>\u2022\u00a0\u00a0Correction d&#8217;un bogue mineur avec le casque ne se connectant pas \u00e0 une t\u00e9l\u00e9commande apr\u00e8s l&#8217;avoir coupl\u00e9 initialement<\/p>\n","protected":false},"featured_media":0,"template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SENA PUBLIE LE NOUVEAU FIRMWARE POUR LA S\u00c9RIE SPIDER, 50R, 50S, 5S, ET STRYKER - SENA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Best Motorcycle &amp; Action Sport Bluetooth Devices | Sena\" \/>\n<meta property=\"og:description\" content=\"Sena&#039;s motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/\" \/>\n<meta property=\"og:site_name\" content=\"SENA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SenaBluetooth\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T01:53:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sena.com\/wp-content\/themes\/sena\/assets\/images\/common\/og.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"SENA PUBLIE LE NOUVEAU FIRMWARE POUR LA S\u00c9RIE SPIDER, 50R, 50S, 5S, ET STRYKER\" \/>\n<meta name=\"twitter:site\" content=\"@senabluetooth\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/\",\"url\":\"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/\",\"name\":\"SENA PUBLIE LE NOUVEAU FIRMWARE POUR LA S\u00c9RIE SPIDER, 50R, 50S, 5S, ET STRYKER - SENA\",\"isPartOf\":{\"@id\":\"https:\/\/www.sena.com\/#website\"},\"datePublished\":\"2022-06-10T08:55:00+00:00\",\"dateModified\":\"2024-01-31T01:53:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sena.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SENA PUBLIE LE NOUVEAU FIRMWARE POUR LA S\u00c9RIE SPIDER, 50R, 50S, 5S, ET STRYKER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sena.com\/#website\",\"url\":\"https:\/\/www.sena.com\/\",\"name\":\"SENA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.sena.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sena.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sena.com\/#organization\",\"name\":\"SENA\",\"url\":\"https:\/\/www.sena.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"contentUrl\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"width\":1,\"height\":1,\"caption\":\"SENA\"},\"image\":{\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SenaBluetooth\",\"https:\/\/twitter.com\/senabluetooth\",\"https:\/\/www.instagram.com\/senabluetooth\/\",\"https:\/\/www.youtube.com\/senabluetooth\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SENA PUBLIE LE NOUVEAU FIRMWARE POUR LA S\u00c9RIE SPIDER, 50R, 50S, 5S, ET STRYKER - SENA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/","og_locale":"fr_FR","og_type":"article","og_title":"The Best Motorcycle & Action Sport Bluetooth Devices | Sena","og_description":"Sena's motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.","og_url":"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/","og_site_name":"SENA","article_publisher":"https:\/\/www.facebook.com\/SenaBluetooth","article_modified_time":"2024-01-31T01:53:31+00:00","og_image":[{"url":"https:\/\/www.sena.com\/wp-content\/themes\/sena\/assets\/images\/common\/og.jpg","width":1200,"height":630,"type":""}],"twitter_card":"summary_large_image","twitter_title":"SENA PUBLIE LE NOUVEAU FIRMWARE POUR LA S\u00c9RIE SPIDER, 50R, 50S, 5S, ET STRYKER","twitter_site":"@senabluetooth","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/","url":"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/","name":"SENA PUBLIE LE NOUVEAU FIRMWARE POUR LA S\u00c9RIE SPIDER, 50R, 50S, 5S, ET STRYKER - SENA","isPartOf":{"@id":"https:\/\/www.sena.com\/#website"},"datePublished":"2022-06-10T08:55:00+00:00","dateModified":"2024-01-31T01:53:31+00:00","breadcrumb":{"@id":"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sena.com\/fr\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-series-50r-50s-5s-stryker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sena.com\/fr\/"},{"@type":"ListItem","position":2,"name":"SENA PUBLIE LE NOUVEAU FIRMWARE POUR LA S\u00c9RIE SPIDER, 50R, 50S, 5S, ET STRYKER"}]},{"@type":"WebSite","@id":"https:\/\/www.sena.com\/#website","url":"https:\/\/www.sena.com\/","name":"SENA","description":"","publisher":{"@id":"https:\/\/www.sena.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sena.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.sena.com\/#organization","name":"SENA","url":"https:\/\/www.sena.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","contentUrl":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","width":1,"height":1,"caption":"SENA"},"image":{"@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SenaBluetooth","https:\/\/twitter.com\/senabluetooth","https:\/\/www.instagram.com\/senabluetooth\/","https:\/\/www.youtube.com\/senabluetooth"]}]}},"_links":{"self":[{"href":"https:\/\/www.sena.com\/fr\/wp-json\/wp\/v2\/post_notice\/26598"}],"collection":[{"href":"https:\/\/www.sena.com\/fr\/wp-json\/wp\/v2\/post_notice"}],"about":[{"href":"https:\/\/www.sena.com\/fr\/wp-json\/wp\/v2\/types\/post_notice"}],"wp:attachment":[{"href":"https:\/\/www.sena.com\/fr\/wp-json\/wp\/v2\/media?parent=26598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}