{"id":25991,"date":"2023-04-19T17:49:00","date_gmt":"2023-04-19T08:49:00","guid":{"rendered":"https:\/\/www.sena.com\/stories\/disclosure\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/"},"modified":"2024-01-31T16:32:27","modified_gmt":"2024-01-31T07:32:27","slug":"sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2","status":"publish","type":"post_notice","link":"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/","title":{"rendered":"SENA VER\u00d6FFENTLICHT NEUE FIRMWARE F\u00dcR DIE SPIDER ST-1 &amp; SPIDER RT-1"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">SPIDER-ST1 Firmware v1.2 (f\u00fcr SPIDER-ST1-01, SPIDER-ST1-01D)<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Die Mikrofonempfindlichkeit wurde verbessert<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung, bei der sich die maximale Lautst\u00e4rke je nach Lautst\u00e4rke von Mesh Intercom \u00e4ndert<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei der \u00c4nderung der Musiklautst\u00e4rke beim Ein- und Ausschalten von Mesh Intercom<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung f\u00fcr das Empfangen und \u00dcbertragen von Audio bei Verbindung mit einem Honda Gold Wing Infotainmentsystem<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SPIDER-ST1 Firmware v2.1 (f\u00fcr SPIDER-ST1-10, SPIDER-ST1-10D)<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Unterst\u00fctzung f\u00fcr die 2022er Versionen von RC3 und RC4 hinzugef\u00fcgt<br>\u2022\u00a0\u00a0Synchronisierung der Lautst\u00e4rke zwischen einem BWM Mottorad TFT-Display und dem Headset wurde hinzugef\u00fcgt<br>\u2022\u00a0\u00a0Anpassung der Lautst\u00e4rkeregelung bei aktivierter Audio Overlay Volume Management-Einstellung Die Audioqualit\u00e4t und Stabilit\u00e4t von Mesh Intercom wurde verbessert<br><br>Telefonanruf<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei der Annahme eines Anrufs von einer anderen Person w\u00e4hrend eines laufenden Telefongespr\u00e4chs<br>\u2022\u00a0\u00a0Geringf\u00fcgige Fehlerbehebung bei der Kurzwahlfunktion, wenn ein zweites gekoppeltes Telefon zum Telefonieren verwendet wird<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei Sprachproblemen bei Telefonanrufen mit Honda Gold Wing Motorr\u00e4dern<br>\u2022\u00a0\u00a0Die Aktion &#8220;Letztes Ger\u00e4t wieder verbinden&#8221; wurde hinzugef\u00fcgt. <br><br>Gegensprechanlage<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung beim Empfang eines Telefonanrufs w\u00e4hrend Mesh Intercom<br>\u2022\u00a0\u00a0Geringf\u00fcgige Fehlerbehebung bei WeChat-Sprachanrufen, die w\u00e4hrend Musik und Interkom-\u00dcberlagerung funktionieren<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei Mesh Intercom, wenn ein digitaler Assistent auf einem gekoppelten Smartphone aktiviert wird, das keinen digitalen Assistenten unterst\u00fctzt<br>\u2022\u00a0\u00a0Verbessertes Einschalten des Mikrofons, wenn Mesh Intercom neu gestartet wurde<br><br>VOX-Telefon<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei der \u00c4nderung der VOX-Empfindlichkeit w\u00e4hrend eines eingehenden Anrufs<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei der VOX Phone Funktion, wenn w\u00e4hrend eines laufenden Telefonats ein Anruf eingeht<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei der VOX-Telefonfunktion, die auf einigen chinesischen Telefonen nicht richtig funktioniert<br>\u2022\u00a0\u00a0Verbesserung der Leistung der VOX-Telefonfunktion<br><br>APP<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei der korrekten Anzeige des Lautst\u00e4rkepegels, wenn HFP und A2DP nicht funktionieren<br><br>Ansage und Ton<br>\u2022\u00a0\u00a0Die Geschwindigkeit der Sprachansagen wurde um 10% erh\u00f6ht<br>\u2022\u00a0\u00a0Ton zum Abweisen eines Anrufs hinzugef\u00fcgt<br>\u2022\u00a0\u00a0Es wurde ein Ton f\u00fcr die Erstellung einer Kurzwahlvoreinstellung hinzugef\u00fcgt<br>\u2022\u00a0\u00a0Es wurde ein Ton hinzugef\u00fcgt, wenn eine Kurzwahlvoreinstellung aktiviert wird<br>\u2022\u00a0\u00a0Der Ton f\u00fcr den n\u00e4chsten und vorherigen Musiktitel wurde von Double-Mid auf Single-Mid ge\u00e4ndert<br>\u2022\u00a0\u00a0Die Sprachansage und der Ton f\u00fcr Mesh Grouping wurden ge\u00e4ndert<br>\u2022\u00a0\u00a0Ein kleiner Fehler wurde behoben, bei dem sich das Ger\u00e4t nach 4 T\u00f6nen bei niedrigem Batteriestand ausschaltete.<br>\u2022\u00a0\u00a0Vor der Sprachansage zur Warnung bei niedrigem Batteriestand wurde ein Warnton hinzugef\u00fcgt<br>\u2022\u00a0\u00a0Sprachansage zur Warnung bei niedrigem Batteriestand hinzugef\u00fcgt, wenn die Batterie nicht gen\u00fcgend Energie hat<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung, bei der die Sprachansage bei niedrigem Akkustand zweimal abgespielt wurde<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung, bei der der Ton beim Aufrufen des Konfigurationsmen\u00fcs zweimal abgespielt wurde<br><br>LED<br>\u2022\u00a0\u00a0Die rote LED leuchtet jetzt 2 Sekunden lang, wenn die Bluetooth-Erkennung abgeschlossen ist.<br>\u2022\u00a0\u00a0Die blaue LED leuchtet nun zweimal, wenn ein digitaler Assistent verwendet wird.<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei der Lade-LED, die sich nicht \u00e4ndert, wenn das Ladekabel eingesteckt oder abgezogen wird, w\u00e4hrend das Ger\u00e4t eingeschaltet ist <br><br>MISC<br>\u2022\u00a0\u00a0Es wurde eine spezielle Sprachansage hinzugef\u00fcgt, die zu h\u00f6ren ist, wenn die Sprachansageoptionen in der Sena Motorcycles App deaktiviert sind.<br>\u2022\u00a0\u00a0Geringf\u00fcgige Fehlerbehebung bei der Option zum Zur\u00fccksetzen auf die Werkseinstellungen im Konfigurationsmen\u00fc, bei der die Zeit nicht abl\u00e4uft<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung beim automatischen Beenden des Konfigurationsmen\u00fcs, wenn ein Smartphone angeschlossen ist<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SPIDER-ST1 Firmware v2.1.1 (f\u00fcr SPIDER-ST1-10, SPIDER-ST1-10D)<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Unterst\u00fctzung f\u00fcr RC3- und RC4-Fernbedienungen hinzugef\u00fcgt<br>\u2022\u00a0\u00a0Die Sprachansage \u201eFernbedienung getrennt\u201c wurde hinzugef\u00fcgt, wenn eine Fernbedienung getrennt wird<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SPIDER-RT1 Firmware v1.2<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Die Mikrofonempfindlichkeit wurde verbessert<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung, bei der sich die maximale Lautst\u00e4rke je nach Lautst\u00e4rke von Mesh Intercom \u00e4ndert<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung bei der \u00c4nderung der Musiklautst\u00e4rke beim Ein- und Ausschalten von Mesh Intercom<br>\u2022\u00a0\u00a0Kleinere Fehlerbehebung f\u00fcr das Empfangen und \u00dcbertragen von Audio bei Verbindung mit einem Honda Gold Wing Infotainmentsystem<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SPIDER-RT1 Firmware v2.1 (f\u00fcr SPIDER-RT1-10, SPIDER-RT1-10D)<\/h3>\n\n\n\n<p>\u2022&nbsp;&nbsp;Unterst\u00fctzung f\u00fcr die 2022er Versionen von RC3 und RC4 hinzugef\u00fcgt<br>\u2022&nbsp;&nbsp;Synchronisierung der Lautst\u00e4rke zwischen einem BWM Mottorad TFT-Display und dem Headset wurde hinzugef\u00fcgt<br>\u2022&nbsp;&nbsp;Anpassung der Lautst\u00e4rkeregelung bei aktivierter Audio Overlay Volume Management-Einstellung Die Audioqualit\u00e4t und Stabilit\u00e4t von Mesh Intercom wurde verbessert<\/p>\n\n\n\n<p>Telefonanruf<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung bei der Annahme eines Anrufs von einer anderen Person w\u00e4hrend eines laufenden Telefongespr\u00e4chs<br>\u2022&nbsp;&nbsp;Geringf\u00fcgige Fehlerbehebung bei der Kurzwahlfunktion, wenn ein zweites gekoppeltes Telefon zum Telefonieren verwendet wird<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung bei Sprachproblemen bei Telefonanrufen mit Honda Gold Wing Motorr\u00e4dern<br>\u2022&nbsp;&nbsp;Die Aktion &#8220;Letztes Ger\u00e4t wieder verbinden&#8221; wurde hinzugef\u00fcgt.<\/p>\n\n\n\n<p>Gegensprechanlage<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung beim Empfang eines Telefonanrufs w\u00e4hrend Mesh Intercom<br>\u2022&nbsp;&nbsp;Geringf\u00fcgige Fehlerbehebung bei WeChat-Sprachanrufen, die w\u00e4hrend Musik und Interkom-\u00dcberlagerung funktionieren<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung bei Mesh Intercom, wenn ein digitaler Assistent auf einem gekoppelten Smartphone aktiviert wird, das keinen digitalen Assistenten unterst\u00fctzt<br>\u2022&nbsp;&nbsp;Verbessertes Einschalten des Mikrofons, wenn Mesh Intercom neu gestartet wurde<\/p>\n\n\n\n<p>VOX-Telefon<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung bei der \u00c4nderung der VOX-Empfindlichkeit w\u00e4hrend eines eingehenden Anrufs<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung bei der VOX Phone Funktion, wenn w\u00e4hrend eines laufenden Telefonats ein Anruf eingeht<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung bei der VOX-Telefonfunktion, die auf einigen chinesischen Telefonen nicht richtig funktioniert<br>\u2022&nbsp;&nbsp;Verbesserung der Leistung der VOX-Telefonfunktion<\/p>\n\n\n\n<p>APP<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung bei der korrekten Anzeige des Lautst\u00e4rkepegels, wenn HFP und A2DP nicht funktionieren<\/p>\n\n\n\n<p>Ansage und Ton<br>\u2022&nbsp;&nbsp;Die Geschwindigkeit der Sprachansagen wurde um 10% erh\u00f6ht<br>\u2022&nbsp;&nbsp;Ton zum Abweisen eines Anrufs hinzugef\u00fcgt<br>\u2022&nbsp;&nbsp;Es wurde ein Ton f\u00fcr die Erstellung einer Kurzwahlvoreinstellung hinzugef\u00fcgt<br>\u2022&nbsp;&nbsp;Es wurde ein Ton hinzugef\u00fcgt, wenn eine Kurzwahlvoreinstellung aktiviert wird<br>\u2022&nbsp;&nbsp;Der Ton f\u00fcr den n\u00e4chsten und vorherigen Musiktitel wurde von Double-Mid auf Single-Mid ge\u00e4ndert<br>\u2022&nbsp;&nbsp;Die Sprachansage und der Ton f\u00fcr Mesh Grouping wurden ge\u00e4ndert<br>\u2022&nbsp;&nbsp;Ein kleiner Fehler wurde behoben, bei dem sich das Ger\u00e4t nach 4 T\u00f6nen bei niedrigem Batteriestand ausschaltete.<br>\u2022&nbsp;&nbsp;Vor der Sprachansage zur Warnung bei niedrigem Batteriestand wurde ein Warnton hinzugef\u00fcgt<br>\u2022&nbsp;&nbsp;Sprachansage zur Warnung bei niedrigem Batteriestand hinzugef\u00fcgt, wenn die Batterie nicht gen\u00fcgend Energie hat<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung, bei der die Sprachansage bei niedrigem Akkustand zweimal abgespielt wurde<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung, bei der der Ton beim Aufrufen des Konfigurationsmen\u00fcs zweimal abgespielt wurde<\/p>\n\n\n\n<p>LED<br>\u2022&nbsp;&nbsp;Die rote LED leuchtet jetzt 2 Sekunden lang, wenn die Bluetooth-Erkennung abgeschlossen ist.<br>\u2022&nbsp;&nbsp;Die blaue LED leuchtet nun zweimal, wenn ein digitaler Assistent verwendet wird.<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung bei der Lade-LED, die sich nicht \u00e4ndert, wenn das Ladekabel eingesteckt oder abgezogen wird, w\u00e4hrend das Ger\u00e4t eingeschaltet ist<\/p>\n\n\n\n<p>MISC<br>\u2022&nbsp;&nbsp;Es wurde eine spezielle Sprachansage hinzugef\u00fcgt, die zu h\u00f6ren ist, wenn die Sprachansageoptionen in der Sena Motorcycles App deaktiviert sind.<br>\u2022&nbsp;&nbsp;Geringf\u00fcgige Fehlerbehebung bei der Option zum Zur\u00fccksetzen auf die Werkseinstellungen im Konfigurationsmen\u00fc, bei der die Zeit nicht abl\u00e4uft<br>\u2022&nbsp;&nbsp;Kleinere Fehlerbehebung beim automatischen Beenden des Konfigurationsmen\u00fcs, wenn ein Smartphone angeschlossen ist<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SPIDER RT1 v2.1.1 Firmware (f\u00fcr Version 2022 des SPIDER RT1)<\/h3>\n\n\n\n<p>\u2022\u00a0\u00a0Unterst\u00fctzung f\u00fcr die Fernbedienungen RC3 und RC4 wurde hinzugef\u00fcgt<br>\u2022\u00a0\u00a0Die Sprachansage \u201eFernbedienung getrennt\u201c wurde hinzugef\u00fcgt, wenn eine Fernbedienung getrennt wird.<\/p>\n","protected":false},"featured_media":0,"template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SENA VER\u00d6FFENTLICHT NEUE FIRMWARE F\u00dcR DIE SPIDER ST-1 &amp; SPIDER RT-1 - SENA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Best Motorcycle &amp; Action Sport Bluetooth Devices | Sena\" \/>\n<meta property=\"og:description\" content=\"Sena&#039;s motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SENA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SenaBluetooth\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-31T07:32:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sena.com\/wp-content\/themes\/sena\/assets\/images\/common\/og.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"SENA VER\u00d6FFENTLICHT NEUE FIRMWARE F\u00dcR DIE SPIDER ST-1 &amp; SPIDER RT-1\" \/>\n<meta name=\"twitter:site\" content=\"@senabluetooth\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/\",\"url\":\"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/\",\"name\":\"SENA VER\u00d6FFENTLICHT NEUE FIRMWARE F\u00dcR DIE SPIDER ST-1 &amp; SPIDER RT-1 - SENA\",\"isPartOf\":{\"@id\":\"https:\/\/www.sena.com\/#website\"},\"datePublished\":\"2023-04-19T08:49:00+00:00\",\"dateModified\":\"2024-01-31T07:32:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sena.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SENA VER\u00d6FFENTLICHT NEUE FIRMWARE F\u00dcR DIE SPIDER ST-1 &amp; SPIDER RT-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sena.com\/#website\",\"url\":\"https:\/\/www.sena.com\/\",\"name\":\"SENA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.sena.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sena.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sena.com\/#organization\",\"name\":\"SENA\",\"url\":\"https:\/\/www.sena.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"contentUrl\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"width\":1,\"height\":1,\"caption\":\"SENA\"},\"image\":{\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SenaBluetooth\",\"https:\/\/twitter.com\/senabluetooth\",\"https:\/\/www.instagram.com\/senabluetooth\/\",\"https:\/\/www.youtube.com\/senabluetooth\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SENA VER\u00d6FFENTLICHT NEUE FIRMWARE F\u00dcR DIE SPIDER ST-1 &amp; SPIDER RT-1 - SENA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/","og_locale":"de_DE","og_type":"article","og_title":"The Best Motorcycle & Action Sport Bluetooth Devices | Sena","og_description":"Sena's motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.","og_url":"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/","og_site_name":"SENA","article_publisher":"https:\/\/www.facebook.com\/SenaBluetooth","article_modified_time":"2024-01-31T07:32:27+00:00","og_image":[{"url":"https:\/\/www.sena.com\/wp-content\/themes\/sena\/assets\/images\/common\/og.jpg","width":1200,"height":630,"type":""}],"twitter_card":"summary_large_image","twitter_title":"SENA VER\u00d6FFENTLICHT NEUE FIRMWARE F\u00dcR DIE SPIDER ST-1 &amp; SPIDER RT-1","twitter_site":"@senabluetooth","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/","url":"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/","name":"SENA VER\u00d6FFENTLICHT NEUE FIRMWARE F\u00dcR DIE SPIDER ST-1 &amp; SPIDER RT-1 - SENA","isPartOf":{"@id":"https:\/\/www.sena.com\/#website"},"datePublished":"2023-04-19T08:49:00+00:00","dateModified":"2024-01-31T07:32:27+00:00","breadcrumb":{"@id":"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sena.com\/de\/stories\/notice\/sena-releases-firmware-updates-for-the-spider-st1-spider-rt1-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sena.com\/de\/"},{"@type":"ListItem","position":2,"name":"SENA VER\u00d6FFENTLICHT NEUE FIRMWARE F\u00dcR DIE SPIDER ST-1 &amp; SPIDER RT-1"}]},{"@type":"WebSite","@id":"https:\/\/www.sena.com\/#website","url":"https:\/\/www.sena.com\/","name":"SENA","description":"","publisher":{"@id":"https:\/\/www.sena.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sena.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.sena.com\/#organization","name":"SENA","url":"https:\/\/www.sena.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","contentUrl":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","width":1,"height":1,"caption":"SENA"},"image":{"@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SenaBluetooth","https:\/\/twitter.com\/senabluetooth","https:\/\/www.instagram.com\/senabluetooth\/","https:\/\/www.youtube.com\/senabluetooth"]}]}},"_links":{"self":[{"href":"https:\/\/www.sena.com\/de\/wp-json\/wp\/v2\/post_notice\/25991"}],"collection":[{"href":"https:\/\/www.sena.com\/de\/wp-json\/wp\/v2\/post_notice"}],"about":[{"href":"https:\/\/www.sena.com\/de\/wp-json\/wp\/v2\/types\/post_notice"}],"wp:attachment":[{"href":"https:\/\/www.sena.com\/de\/wp-json\/wp\/v2\/media?parent=25991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}