{"id":24161,"date":"2022-07-13T13:47:00","date_gmt":"2022-07-13T04:47:00","guid":{"rendered":"https:\/\/www.sena.com\/post_news\/sena-at-the-2022-edition-of-eurobike\/"},"modified":"2024-01-29T14:58:04","modified_gmt":"2024-01-29T05:58:04","slug":"sena-at-the-2022-edition-of-eurobike","status":"publish","type":"post_news","link":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/","title":{"rendered":"SENA AUF DER EUROBIKE 2022"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"370\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img1-1024x370.jpg\" alt=\"\" class=\"wp-image-24079\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img1-1024x370.jpg 1024w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img1-300x109.jpg 300w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img1-768x278.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>FRANKFURT (13. bis 17. Juli 2022)&nbsp;\u2013&nbsp;<\/strong>Sena Technologies Inc., das f\u00fchrende Unternehmen im Bereich der Zweiradkommunikation, wird auf der Eurobike 2022 vertreten sein, die zum ersten Mal auf dem Frankfurter Messegel\u00e4nde stattfindet.<br>&nbsp;<br>Die&nbsp;<a href=\"https:\/\/www.eurobike.com\/en\/\">EUROBIKE<\/a>&nbsp;ist die zentrale Plattform f\u00fcr die Welt des Fahrrads und der zuk\u00fcnftigen Mobilit\u00e4t. Sie spielt eine wichtige Rolle bei der Umgestaltung des Energie- und Verkehrssektors, treibt den sozialen Wandel voran und setzt neue Ma\u00dfst\u00e4be in den Bereichen Sport, Freizeit, Gesundheit und Mobilit\u00e4t.<br><br>Nach drei Tagen, die den Fachleuten und der Presse gewidmet sind, \u00f6ffnet die Veranstaltung am Wochenende des 16. und 17. Juli ihre Pforten f\u00fcr die \u00d6ffentlichkeit, die in gro\u00dfer Zahl erwartet wird.<br><br>Neben Veranstaltungen, Workshops und Testbereichen finden Sie den Sena-Stand in Halle 9, Stand A11.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img2-1024x683.jpg\" alt=\"\" class=\"wp-image-24087\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img2-1024x683.jpg 1024w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img2-300x200.jpg 300w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img2-768x512.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img2.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">ENTDECKEN SIE DIE SENA PRODUKTE<\/h3>\n\n\n\n<p>Nach Jahren der technischen Erfahrung und des Fortschritts in der Branche der Kommunikationssysteme und intelligenten Helme f\u00fcr Motorradfahrer, hat Sena sein Know-how und seine technologische Kompetenz in den Dienst der Fahrradliebhaber gestellt. Die Idee ist, Sicherheit und Technologie zu kombinieren, indem eine Produktlinie angeboten wird, die dem Bed\u00fcrfnis der \u00d6ffentlichkeit nach intelligenter Mobilit\u00e4t und Konnektivit\u00e4t am besten entspricht.<br><br>Alle Produkte von Sena bieten eine direkte Helm-zu-Helm-Kommunikation \u00fcber die Intercom-Technologie und Konnektivit\u00e4t mit dem Smartphone, um Musik zu h\u00f6ren, GPS-Routen zu verfolgen, Feedback von Fitness-Apps zu erhalten oder Anrufe entgegenzunehmen. Sena hat au\u00dferdem eine eigene App entwickelt, mit der sich die Funktionen des Ger\u00e4ts bequem \u00fcber den Bildschirm des Smartphones steuern lassen.<br><br>Bei den Smart Helmen ist das Mikrofon in den vorderen Teil der Helmschale integriert und \u00fcbertr\u00e4gt dank der Sena Advanced Noise Control-Technologie, die St\u00f6rungen durch Wind und Hintergrundger\u00e4usche herausfiltert, einen klaren Klang. Die Lautsprecher sind so angebracht, dass sie die Ohren nicht verdecken, damit Sie die Ger\u00e4usche der Stra\u00dfe und der Umgebung wahrnehmen k\u00f6nnen.<br><br>F\u00fcr beste Sicherheit und Sichtbarkeit sorgt das in vielen&nbsp; Modellen integrierte R\u00fccklicht.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img3-1024x683.jpg\" alt=\"\" class=\"wp-image-24095\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img3-1024x683.jpg 1024w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img3-300x200.jpg 300w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img3-768x512.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img3.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mesh &amp; Bluetooth Intercom: Wie funktioniert das?\u00a0<\/h3>\n\n\n\n<p>Sie k\u00f6nnen Helme direkt miteinander verbinden, um in Gruppen \u00fcber Bluetooth Intercom oder \u00fcber Mesh Intercom zu sprechen, je nachdem, welches Smart-Helm-Modell Sie w\u00e4hlen. Es ist keine Smartphone-Verbindung oder Nutzung von Internetdatenverkehr erforderlich.<br><br>Bluetooth Intercom kann bis zu 4 Benutzer in HD-Audioqualit\u00e4t miteinander verbinden.<br><br>Mesh Intercom verbindet automatisch alle kompatiblen Ger\u00e4te in der Reichweite ohne Begrenzung der Anzahl der Verbindungen oder zus\u00e4tzliches Pairing und ist daher perfekt f\u00fcr Gruppenfahrten. Mesh Intercom-Benutzer k\u00f6nnen dank der 9 Kan\u00e4le der Mesh-Plattform auch Untergruppen bilden; eine Branchenneuheit.*<br><br>* Bluetooth Intercom und Mesh Intercom Modelle sind nicht miteinander kompatibel.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-red-color has-text-color\">Was Sie am Sena-Stand finden werden:<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">DIE RADSPORT-PRODUKTLINIE, DIE SIE KENNEN UND LIEBEN!<\/h3>\n\n\n\n<p>M1\/M1EVO&nbsp;: F\u00fcr Mountainbiker und alle, die gerne auf Wanderwegen, in W\u00e4ldern und auf unbefestigten Stra\u00dfen unterwegs sind<br>R1\/R1 EVO&nbsp;: Perfekt f\u00fcr die Stadt und Schotterwege<br>R2\/R2 EVO&nbsp;: Rennradhelm mit einem sportlichen und aerodynamischen Desig<br><br>Die oben aufgef\u00fchrten Modelle sind in der Bluetooth Intercom-Version erh\u00e4ltlich, die bis zu 4 Personen innerhalb eines 900-Meter-Radius verbindet, und in der EVO-Version mit Mesh Intercom f\u00fcr praktisch unbegrenzte Verbindungen innerhalb eines 900-Meter-Radius &#8211; erweiterbar auf 3,6 km mit mindestens 6 Radfahrern &#8211; und mit der Multi Channel Open Mesh-Technologie mit 9 Kan\u00e4len.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"479\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img4-1024x479.jpg\" alt=\"\" class=\"wp-image-24103\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img4-1024x479.jpg 1024w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img4-300x140.jpg 300w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img4-768x359.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img4.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Rumba&nbsp;: Smart Helm mit einem urbanen Look geeignet f\u00fcr Radfahren, sondern auch f\u00fcr den Einsatz auf einem Scooter, Skateboard oder Roller dank der Doppel-Zertifizierung. Die Bluetooth-Gegensprechanlage verbindet zwei Benutzer in einer Entfernung von bis zu 200 Metern.<br><br>Pi&nbsp;: Pi verwandelt Ihren Lieblingsfahrradhelm in einen Smart Helm. Hauptmodul\/Akku und Lautsprecher werden an den seitlichen Helmriemen befestigt und verf\u00fcgen \u00fcber einen Lautsprecher, ein Mikrofon und eine Zwei-Tasten-Steuerung. Pi kann zwei Radfahrer mit einer Reichweite von bis zu 400 Metern im freien Feld \u00fcber Bluetooth Intercom miteinander verbinden.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-vivid-red-color has-text-color\">2022\/23 NEWS<\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"479\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img5-1024x479.jpg\" alt=\"\" class=\"wp-image-24111\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img5-1024x479.jpg 1024w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img5-300x140.jpg 300w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img5-768x359.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img5.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">SENA C1:\u00a0Weltpremiere<\/h3>\n\n\n\n<p>Mit nur 390 g in Gr\u00f6\u00dfe M ist der C1 der leichteste Sena Smart Helm aller Zeiten!&nbsp;<br>Das Mikrofon ist in der Vorderseite der Schale integriert, und die Lautsprecher befinden sich in den beiden Einheiten, die an den Nylonriemen befestigt sind. Die Position der Lautsprecher ist so gew\u00e4hlt, dass Sie Musik h\u00f6ren oder sich mit Ihren Freunden unterhalten k\u00f6nnen, ohne dass Ihre Wahrnehmung der Umgebung beeintr\u00e4chtigt wird.<br><br>Auf der R\u00fcckseite des Helms befindet sich ein R\u00fccklicht, das auf drei Modi eingestellt werden kann &#8211; Dauerlicht, Nachtblinken und Tagblinken &#8211; um eine maximale Sichtbarkeit auf der Stra\u00dfe zu gew\u00e4hrleisten, sowie drei Tasten zur manuellen Steuerung aller Funktionen des C1.<br><br>Der Sena C1 verf\u00fcgt \u00fcber eine Zwei-Wege-Bluetooth-Gegensprechanlage, \u00fcber die sich zwei Radfahrer innerhalb eines 300-Meter-Radius miteinander verbinden und einfach und intuitiv kommunizieren k\u00f6nnen. Sie m\u00fcssen nicht mehr nebeneinander auf der Fahrbahn stehen, um sich zu unterhalten, und das sorgt f\u00fcr mehr Sicherheit beim Fahren.<br><br>Die Bluetooth 5.1-Technologie erm\u00f6glicht eine stabile und effektive Verbindung mit dem Smartphone, um Musik zu h\u00f6ren, GPS-Routen zu verfolgen und Anrufe entgegenzunehmen, ohne das Radfahren unterbrechen zu m\u00fcssen.<br><br>Der Sena C1 wird in Europa im letzten Quartal 2022 in zwei verschiedenen Varianten erh\u00e4ltlich sein: Mattwei\u00df und Mattgrau.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"479\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img6-1024x479.jpg\" alt=\"\" class=\"wp-image-24119\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img6-1024x479.jpg 1024w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img6-300x140.jpg 300w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img6-768x359.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img6.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">SENA R2X<\/h3>\n\n\n\n<p>Der R2X ist der erste smarte Fahrradhelm mit dem Komfort von Amazon Alexa Built-in.&nbsp;<br><br>Im R2X finden Sie modernste Sena-Kommunikationstechnologie verpackt in einem aerodynamischen Helm, der perfekt f\u00fcr den Stra\u00dfenradsport geeignet ist. Er verf\u00fcgt \u00fcber nahtlos integrierte Lautsprecher und ein Mikrofon, die es den Benutzern erm\u00f6glichen, mit anderen Radfahrern, mit ihren Smartphones und mit Alexa Built-in* zu interagieren.<br><br>Alexa ist die intelligente Cloud-basierte Sprach-KI, mit der Sie \u00fcber den R2X sprechen k\u00f6nnen. Sprechen Sie mit Alexa \u00fcber Ihren Helm, um Musik abzuspielen, die Nachrichten zu h\u00f6ren, das Wetter abzufragen, Smart-Home-Ger\u00e4te zu steuern und vieles mehr &#8211; und das alles, w\u00e4hrend Sie Ihre H\u00e4nde am Lenker und Ihre Augen auf der Stra\u00dfe lassen. Die Verwendung von Alexa auf dem R2X ist einfach und bedienerfreundlich: Sie brauchen nur zu fragen, und Alexa antwortet sofort. Versuchen Sie zu fragen: &#8220;Alexa, ich komme nach Hause, schalte die Klimaanlage ein&#8221; oder &#8220;Alexa, \u00f6ffne das Garagentor&#8221; &#8211; so einfach ist das! Stellen Sie nur sicher, dass Sie Ihr Smartphone mit der installierten Amazon Alexa App dabei haben.<br><br>Die Mesh-Intercom-Kommunikationsplattform bietet maximale Flexibilit\u00e4t bei Helm-zu-Helm-Verbindungen und ist in der Lage, sich automatisch mit allen kompatiblen Sena Mesh-Ger\u00e4ten in der Reichweite des Helms zu verbinden, ohne Beschr\u00e4nkungen bei der Anzahl der Verbindungen und ohne Kopplungsverfahren. R2X ist mit allen EVO-Ger\u00e4ten der Sena Radsport-Produktlinie wie R1EVO, M1EVO, R2EVO kompatibel. Nicht zuletzt bietet die Funktion Multichannel Open Mesh 9 Kan\u00e4le, mit denen Sie zwischen Gruppen auf verschiedenen Frequenzen wechseln k\u00f6nnen.<br><br>Der R2X mit seiner Polycarbonat-Schale ist f\u00fcr maximalen Komfort und Sicherheit konzipiert. F\u00fcr beste Sichtbarkeit unter allen Bedingungen verf\u00fcgt es \u00fcber ein integriertes R\u00fccklicht, das in drei verschiedenen Intensit\u00e4ten eingestellt werden kann.<br><br>Die robuste Bluetooth 5.1-Konnektivit\u00e4t mit Ihrem Smartphone erm\u00f6glicht es Ihnen, unterwegs immer Zugriff auf die Funktionen Ihres Telefons zu haben. Mit der Sena Cycling App k\u00f6nnen Nutzer die Einstellungen des R2X Smart Helms verwalten, wie z.B. das Erstellen einer Mesh Intercom Gruppe, das Einstellen der R\u00fccklichtintensit\u00e4t, das Ausw\u00e4hlen der Sprache f\u00fcr die Sprachansagen und vieles mehr direkt \u00fcber den Bildschirm ihres Smartphones.<br><br>Der R2X wird voraussichtlich im kommenden Herbst in Europa erh\u00e4ltlich sein.<br><br>*Alexa Built-in (ABI) ist ein Amazon-Zertifizierungsprogramm, das best\u00e4tigt, ob ein Produkt den Amazon-Standards entspricht und dazu beitr\u00e4gt, dass Kunden ein besseres Alexa-Erlebnis haben.<br><br>**Amazon, Alexa und alle zugeh\u00f6rigen Logos sind Marken von Amazon.com, Inc. oder seinen Tochtergesellschaften.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"684\" src=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img7-1024x684.jpg\" alt=\"\" class=\"wp-image-24127\" srcset=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img7-1024x684.jpg 1024w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img7-300x200.jpg 300w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img7-768x513.jpg 768w, https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_img7.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>EIN BLICK IN DIE ZUKUNFT<\/strong><\/h3>\n\n\n\n<p>F\u00fcr die nahe Zukunft plant Sena seine Partnerschaften mit namhaften Unternehmen der Radsportbranche zu erweitern und bereits bestehende Technologien weiterzuentwickeln.<br><br>Sena ist offizieller Partner des professionellen World Tour Teams\u00a0<a href=\"https:\/\/www.team-dsm.com\/\">Team DSM<\/a>\u00a0f\u00fcr die Kommunikation w\u00e4hrend des Rennens. Die Ingenieure von SENA arbeiten eng mit den Forschungs- und Entwicklungsexperten von Team DSM zusammen, um ein \u00fcberlegenes Kommunikationssystem zu entwickeln, das den Kontakt zwischen Fahrern und Trainern deutlich verbessert.<br><br>Die Zusammenarbeit mit einer Reihe von Profiteams, darunter auch das\u00a0<a href=\"https:\/\/www.team-dsm.com\/\">Team DSM<\/a>, das die technologische Forschung und Entwicklung im Bereich der sportlichen Leistung zu seinen St\u00e4rken z\u00e4hlt, wird es Sena erm\u00f6glichen, ein Produkt zu entwickeln, das speziell f\u00fcr den Radsport entwickelt wurde und in der Lage ist, die Teamarbeit und die individuelle sportliche Leistung zu verbessern.<br><br>Partnerschaften mit Profisportlern sind f\u00fcr Sena \u00e4u\u00dferst wertvoll, da sie es dem Unternehmen erm\u00f6glichen, die Bed\u00fcrfnisse der Branche besser zu verstehen und seine Produkte zu verbessern und weiterzuentwickeln, um die anspruchsvollsten Standards zu erf\u00fcllen.<br><br>Sena freut sich darauf, sein Netzwerk mit immer mehr wichtigen Akteuren und Enthusiasten in der Branche zu erweitern und das #rideconnected-Erlebnis allen Radfahrern zug\u00e4nglich zu machen.\u00a0<br><br>Das komplette Media-Kit finden sie\u00a0hier.<\/p>\n","protected":false},"featured_media":24139,"template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SENA AUF DER EUROBIKE 2022 - SENA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Best Motorcycle &amp; Action Sport Bluetooth Devices | Sena\" \/>\n<meta property=\"og:description\" content=\"Sena&#039;s motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/\" \/>\n<meta property=\"og:site_name\" content=\"SENA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SenaBluetooth\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-29T05:58:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_preview.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"470\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"SENA AUF DER EUROBIKE 2022\" \/>\n<meta name=\"twitter:site\" content=\"@senabluetooth\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/\",\"url\":\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/\",\"name\":\"SENA AUF DER EUROBIKE 2022 - SENA\",\"isPartOf\":{\"@id\":\"https:\/\/www.sena.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_preview.jpg\",\"datePublished\":\"2022-07-13T04:47:00+00:00\",\"dateModified\":\"2024-01-29T05:58:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#primaryimage\",\"url\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_preview.jpg\",\"contentUrl\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_preview.jpg\",\"width\":470,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sena.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SENA AUF DER EUROBIKE 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sena.com\/#website\",\"url\":\"https:\/\/www.sena.com\/\",\"name\":\"SENA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.sena.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sena.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sena.com\/#organization\",\"name\":\"SENA\",\"url\":\"https:\/\/www.sena.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"contentUrl\":\"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg\",\"width\":1,\"height\":1,\"caption\":\"SENA\"},\"image\":{\"@id\":\"https:\/\/www.sena.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/SenaBluetooth\",\"https:\/\/twitter.com\/senabluetooth\",\"https:\/\/www.instagram.com\/senabluetooth\/\",\"https:\/\/www.youtube.com\/senabluetooth\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SENA AUF DER EUROBIKE 2022 - SENA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/","og_locale":"de_DE","og_type":"article","og_title":"The Best Motorcycle & Action Sport Bluetooth Devices | Sena","og_description":"Sena's motorcycle Bluetooth communication devices and video imaging systems are designed to inspire your pursuit of adventure. Find out how here.","og_url":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/","og_site_name":"SENA","article_publisher":"https:\/\/www.facebook.com\/SenaBluetooth","article_modified_time":"2024-01-29T05:58:04+00:00","og_image":[{"width":470,"height":470,"url":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_preview.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"SENA AUF DER EUROBIKE 2022","twitter_site":"@senabluetooth","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/","url":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/","name":"SENA AUF DER EUROBIKE 2022 - SENA","isPartOf":{"@id":"https:\/\/www.sena.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#primaryimage"},"image":{"@id":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_preview.jpg","datePublished":"2022-07-13T04:47:00+00:00","dateModified":"2024-01-29T05:58:04+00:00","breadcrumb":{"@id":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#primaryimage","url":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_preview.jpg","contentUrl":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/01\/sena-x-eurobike_preview.jpg","width":470,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/www.sena.com\/de\/stories\/news\/sena-at-the-2022-edition-of-eurobike\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sena.com\/de\/"},{"@type":"ListItem","position":2,"name":"SENA AUF DER EUROBIKE 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.sena.com\/#website","url":"https:\/\/www.sena.com\/","name":"SENA","description":"","publisher":{"@id":"https:\/\/www.sena.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sena.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.sena.com\/#organization","name":"SENA","url":"https:\/\/www.sena.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","contentUrl":"https:\/\/www.sena.com\/wp-content\/uploads\/2024\/03\/img_logo_red.svg","width":1,"height":1,"caption":"SENA"},"image":{"@id":"https:\/\/www.sena.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SenaBluetooth","https:\/\/twitter.com\/senabluetooth","https:\/\/www.instagram.com\/senabluetooth\/","https:\/\/www.youtube.com\/senabluetooth"]}]}},"_links":{"self":[{"href":"https:\/\/www.sena.com\/de\/wp-json\/wp\/v2\/post_news\/24161"}],"collection":[{"href":"https:\/\/www.sena.com\/de\/wp-json\/wp\/v2\/post_news"}],"about":[{"href":"https:\/\/www.sena.com\/de\/wp-json\/wp\/v2\/types\/post_news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sena.com\/de\/wp-json\/wp\/v2\/media\/24139"}],"wp:attachment":[{"href":"https:\/\/www.sena.com\/de\/wp-json\/wp\/v2\/media?parent=24161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}